{"id":1279,"date":"2025-07-01T18:25:22","date_gmt":"2025-07-01T16:25:22","guid":{"rendered":"https:\/\/poll-berlin.de\/galerie\/?page_id=1279"},"modified":"2025-07-01T18:44:43","modified_gmt":"2025-07-01T16:44:43","slug":"werke-in-sammlungen","status":"publish","type":"page","link":"https:\/\/poll-berlin.de\/galerie\/weitere-kuenstler\/harald-duwe\/werke-in-sammlungen\/","title":{"rendered":"Werke in Sammlungen"},"content":{"rendered":"\n<p><strong>Werke in Sammlungen<\/strong><\/p>\n\n\n\n<p>Kunststiftung Poll, Berlin<br>Sammlung Penz, Berlin<br>Haus der Geschichte der Bundesrepublik Deutschland, Bonn<br>Hans-Christiansen-Haus, Flensburg<br>Sammlung Parabel, Hamburg<br>Hamburger Kunsthalle<br>Kunsthalle zu Kiel<br>Stiftung Schleswig-Holsteinische Landesmuseen, Schleswig<br>Sparkassenstiftung Schleswig-Holstein<br>Hedendaagse Kunst Utrecht<br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Werke in Sammlungen Kunststiftung Poll, BerlinSammlung Penz, BerlinHaus der Geschichte der Bundesrepublik Deutschland, BonnHans-Christiansen-Haus, FlensburgSammlung Parabel, HamburgHamburger KunsthalleKunsthalle zu KielStiftung Schleswig-Holsteinische Landesmuseen, SchleswigSparkassenstiftung Schleswig-HolsteinHedendaagse Kunst Utrecht<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":927,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"kuenstler-text.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1279","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/poll-berlin.de\/galerie\/wp-json\/wp\/v2\/pages\/1279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poll-berlin.de\/galerie\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/poll-berlin.de\/galerie\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/poll-berlin.de\/galerie\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/poll-berlin.de\/galerie\/wp-json\/wp\/v2\/comments?post=1279"}],"version-history":[{"count":4,"href":"https:\/\/poll-berlin.de\/galerie\/wp-json\/wp\/v2\/pages\/1279\/revisions"}],"predecessor-version":[{"id":43342,"href":"https:\/\/poll-berlin.de\/galerie\/wp-json\/wp\/v2\/pages\/1279\/revisions\/43342"}],"up":[{"embeddable":true,"href":"https:\/\/poll-berlin.de\/galerie\/wp-json\/wp\/v2\/pages\/927"}],"wp:attachment":[{"href":"https:\/\/poll-berlin.de\/galerie\/wp-json\/wp\/v2\/media?parent=1279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}